{"id":4444,"date":"2025-01-02T15:32:23","date_gmt":"2025-01-02T15:32:23","guid":{"rendered":"https:\/\/olympicaccessories.com\/product\/brosse-33-cm-avec-poil-en-caoutchouc\/"},"modified":"2025-01-02T15:32:23","modified_gmt":"2025-01-02T15:32:23","slug":"brosse-33-cm-avec-poil-en-caoutchouc","status":"publish","type":"product","link":"https:\/\/olympicaccessories.com\/fr\/produit\/brosse-33-cm-avec-poil-en-caoutchouc\/","title":{"rendered":"Brosse 33 cm avec poil en caoutchouc"},"content":{"rendered":"","protected":false},"excerpt":{"rendered":"","protected":false},"featured_media":4336,"template":"","meta":[],"product_brand":[],"product_cat":[74],"product_tag":[62,67,63],"class_list":["post-4444","product","type-product","status-publish","has-post-thumbnail","product_cat-brosse","product_tag-brosse","product_tag-piscine-creusee","product_tag-piscine-hors-terre","first","outofstock","taxable","shipping-taxable","product-type-simple"],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v28.0 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>Brosse 33 cm avec poil en caoutchouc - Olympic Pool Accessories<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/olympicaccessories.com\/fr\/produit\/brosse-33-cm-avec-poil-en-caoutchouc\/\" \/>\n<meta property=\"og:locale\" content=\"fr_FR\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Brosse 33 cm avec poil en caoutchouc - Olympic Pool Accessories\" \/>\n<meta property=\"og:url\" content=\"https:\/\/olympicaccessories.com\/fr\/produit\/brosse-33-cm-avec-poil-en-caoutchouc\/\" \/>\n<meta property=\"og:site_name\" content=\"Olympic Pool Accessories\" \/>\n<meta property=\"og:image\" content=\"https:\/\/olympicaccessories.com\/wp-content\/uploads\/2025\/01\/Web-img25-22.jpg\" \/>\n\t<meta property=\"og:image:width\" content=\"2083\" \/>\n\t<meta property=\"og:image:height\" content=\"2083\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/olympicaccessories.com\\\/fr\\\/produit\\\/brosse-33-cm-avec-poil-en-caoutchouc\\\/\",\"url\":\"https:\\\/\\\/olympicaccessories.com\\\/fr\\\/produit\\\/brosse-33-cm-avec-poil-en-caoutchouc\\\/\",\"name\":\"Brosse 33 cm avec poil en caoutchouc - Olympic Pool Accessories\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/olympicaccessories.com\\\/fr\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/olympicaccessories.com\\\/fr\\\/produit\\\/brosse-33-cm-avec-poil-en-caoutchouc\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/olympicaccessories.com\\\/fr\\\/produit\\\/brosse-33-cm-avec-poil-en-caoutchouc\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/olympicaccessories.com\\\/wp-content\\\/uploads\\\/2025\\\/01\\\/Web-img25-22.jpg\",\"datePublished\":\"2025-01-02T15:32:23+00:00\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/olympicaccessories.com\\\/fr\\\/produit\\\/brosse-33-cm-avec-poil-en-caoutchouc\\\/#breadcrumb\"},\"inLanguage\":\"fr-FR\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/olympicaccessories.com\\\/fr\\\/produit\\\/brosse-33-cm-avec-poil-en-caoutchouc\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"fr-FR\",\"@id\":\"https:\\\/\\\/olympicaccessories.com\\\/fr\\\/produit\\\/brosse-33-cm-avec-poil-en-caoutchouc\\\/#primaryimage\",\"url\":\"https:\\\/\\\/olympicaccessories.com\\\/wp-content\\\/uploads\\\/2025\\\/01\\\/Web-img25-22.jpg\",\"contentUrl\":\"https:\\\/\\\/olympicaccessories.com\\\/wp-content\\\/uploads\\\/2025\\\/01\\\/Web-img25-22.jpg\",\"width\":2083,\"height\":2083},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/olympicaccessories.com\\\/fr\\\/produit\\\/brosse-33-cm-avec-poil-en-caoutchouc\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\\\/\\\/olympicaccessories.com\\\/fr\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Nos produits\",\"item\":\"https:\\\/\\\/olympicaccessories.com\\\/fr\\\/produits\\\/\"},{\"@type\":\"ListItem\",\"position\":3,\"name\":\"Brosse 33 cm avec poil en caoutchouc\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/olympicaccessories.com\\\/fr\\\/#website\",\"url\":\"https:\\\/\\\/olympicaccessories.com\\\/fr\\\/\",\"name\":\"Olympic Pool Accessories\",\"description\":\"Everything you need for your Pool and Spa\",\"publisher\":{\"@id\":\"https:\\\/\\\/olympicaccessories.com\\\/fr\\\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/olympicaccessories.com\\\/fr\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"fr-FR\"},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/olympicaccessories.com\\\/fr\\\/#organization\",\"name\":\"Olympic Pool Accessories\",\"url\":\"https:\\\/\\\/olympicaccessories.com\\\/fr\\\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"fr-FR\",\"@id\":\"https:\\\/\\\/olympicaccessories.com\\\/fr\\\/#\\\/schema\\\/logo\\\/image\\\/\",\"url\":\"https:\\\/\\\/olympicaccessories.com\\\/wp-content\\\/uploads\\\/2025\\\/12\\\/olympicLogo50_364x128-02.png\",\"contentUrl\":\"https:\\\/\\\/olympicaccessories.com\\\/wp-content\\\/uploads\\\/2025\\\/12\\\/olympicLogo50_364x128-02.png\",\"width\":1518,\"height\":535,\"caption\":\"Olympic Pool Accessories\"},\"image\":{\"@id\":\"https:\\\/\\\/olympicaccessories.com\\\/fr\\\/#\\\/schema\\\/logo\\\/image\\\/\"}}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Brosse 33 cm avec poil en caoutchouc - Olympic Pool Accessories","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/olympicaccessories.com\/fr\/produit\/brosse-33-cm-avec-poil-en-caoutchouc\/","og_locale":"fr_FR","og_type":"article","og_title":"Brosse 33 cm avec poil en caoutchouc - Olympic Pool Accessories","og_url":"https:\/\/olympicaccessories.com\/fr\/produit\/brosse-33-cm-avec-poil-en-caoutchouc\/","og_site_name":"Olympic Pool Accessories","og_image":[{"width":2083,"height":2083,"url":"https:\/\/olympicaccessories.com\/wp-content\/uploads\/2025\/01\/Web-img25-22.jpg","type":"image\/jpeg"}],"twitter_card":"summary_large_image","schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"WebPage","@id":"https:\/\/olympicaccessories.com\/fr\/produit\/brosse-33-cm-avec-poil-en-caoutchouc\/","url":"https:\/\/olympicaccessories.com\/fr\/produit\/brosse-33-cm-avec-poil-en-caoutchouc\/","name":"Brosse 33 cm avec poil en caoutchouc - Olympic Pool Accessories","isPartOf":{"@id":"https:\/\/olympicaccessories.com\/fr\/#website"},"primaryImageOfPage":{"@id":"https:\/\/olympicaccessories.com\/fr\/produit\/brosse-33-cm-avec-poil-en-caoutchouc\/#primaryimage"},"image":{"@id":"https:\/\/olympicaccessories.com\/fr\/produit\/brosse-33-cm-avec-poil-en-caoutchouc\/#primaryimage"},"thumbnailUrl":"https:\/\/olympicaccessories.com\/wp-content\/uploads\/2025\/01\/Web-img25-22.jpg","datePublished":"2025-01-02T15:32:23+00:00","breadcrumb":{"@id":"https:\/\/olympicaccessories.com\/fr\/produit\/brosse-33-cm-avec-poil-en-caoutchouc\/#breadcrumb"},"inLanguage":"fr-FR","potentialAction":[{"@type":"ReadAction","target":["https:\/\/olympicaccessories.com\/fr\/produit\/brosse-33-cm-avec-poil-en-caoutchouc\/"]}]},{"@type":"ImageObject","inLanguage":"fr-FR","@id":"https:\/\/olympicaccessories.com\/fr\/produit\/brosse-33-cm-avec-poil-en-caoutchouc\/#primaryimage","url":"https:\/\/olympicaccessories.com\/wp-content\/uploads\/2025\/01\/Web-img25-22.jpg","contentUrl":"https:\/\/olympicaccessories.com\/wp-content\/uploads\/2025\/01\/Web-img25-22.jpg","width":2083,"height":2083},{"@type":"BreadcrumbList","@id":"https:\/\/olympicaccessories.com\/fr\/produit\/brosse-33-cm-avec-poil-en-caoutchouc\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/olympicaccessories.com\/fr\/"},{"@type":"ListItem","position":2,"name":"Nos produits","item":"https:\/\/olympicaccessories.com\/fr\/produits\/"},{"@type":"ListItem","position":3,"name":"Brosse 33 cm avec poil en caoutchouc"}]},{"@type":"WebSite","@id":"https:\/\/olympicaccessories.com\/fr\/#website","url":"https:\/\/olympicaccessories.com\/fr\/","name":"Olympic Pool Accessories","description":"Everything you need for your Pool and Spa","publisher":{"@id":"https:\/\/olympicaccessories.com\/fr\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/olympicaccessories.com\/fr\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"fr-FR"},{"@type":"Organization","@id":"https:\/\/olympicaccessories.com\/fr\/#organization","name":"Olympic Pool Accessories","url":"https:\/\/olympicaccessories.com\/fr\/","logo":{"@type":"ImageObject","inLanguage":"fr-FR","@id":"https:\/\/olympicaccessories.com\/fr\/#\/schema\/logo\/image\/","url":"https:\/\/olympicaccessories.com\/wp-content\/uploads\/2025\/12\/olympicLogo50_364x128-02.png","contentUrl":"https:\/\/olympicaccessories.com\/wp-content\/uploads\/2025\/12\/olympicLogo50_364x128-02.png","width":1518,"height":535,"caption":"Olympic Pool Accessories"},"image":{"@id":"https:\/\/olympicaccessories.com\/fr\/#\/schema\/logo\/image\/"}}]}},"_links":{"self":[{"href":"https:\/\/olympicaccessories.com\/fr\/wp-json\/wp\/v2\/product\/4444","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/olympicaccessories.com\/fr\/wp-json\/wp\/v2\/product"}],"about":[{"href":"https:\/\/olympicaccessories.com\/fr\/wp-json\/wp\/v2\/types\/product"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/olympicaccessories.com\/fr\/wp-json\/wp\/v2\/media\/4336"}],"wp:attachment":[{"href":"https:\/\/olympicaccessories.com\/fr\/wp-json\/wp\/v2\/media?parent=4444"}],"wp:term":[{"taxonomy":"product_brand","embeddable":true,"href":"https:\/\/olympicaccessories.com\/fr\/wp-json\/wp\/v2\/product_brand?post=4444"},{"taxonomy":"product_cat","embeddable":true,"href":"https:\/\/olympicaccessories.com\/fr\/wp-json\/wp\/v2\/product_cat?post=4444"},{"taxonomy":"product_tag","embeddable":true,"href":"https:\/\/olympicaccessories.com\/fr\/wp-json\/wp\/v2\/product_tag?post=4444"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}